{"id":1978,"date":"2010-02-10T19:02:15","date_gmt":"2010-02-10T21:02:15","guid":{"rendered":"http:\/\/www.consciencia.org\/neiduclos\/?p=1978"},"modified":"2010-02-10T19:02:15","modified_gmt":"2010-02-10T21:02:15","slug":"reinventar-a-roda","status":"publish","type":"post","link":"http:\/\/www.consciencia.org\/neiduclos\/reinventar-a-roda","title":{"rendered":"REINVENTAR A RODA"},"content":{"rendered":"<p><strong>Nei Ducl\u00f3s<br \/>\n<\/strong><br \/>\nConv\u00edvio implica altern\u00e2ncia de pap\u00e9is: num momento somos protagonistas, em outro, coadjuvantes. Mas como em terra de escravos todo mundo \u00e9 senhor, para escapar do estigma, a moda \u00e9 impor o papel principal, jogando fora os demais interlocutores. As m\u00eddias sociais s\u00e3o o para\u00edso desse estado de coisas: todos falam ao mesmo tempo e pouco se presta aten\u00e7\u00e3o ao que se diz fora de cada c\u00edrculo, a n\u00e3o ser para negar ou bater.<\/p>\n<p>N\u00e3o existem mais cal\u00e7adas, conhecidas como passeio p\u00fablico, em que se formavam as rodas da conversa. Nelas, mesmo que houvesse entusiasmo nas falas e urg\u00eancia dos recados, com a algaravia natural produzida por grupos humanos, costumava existir um narrador rodeado de ouvintes. O carisma se exercia nesses espa\u00e7os privilegiados onde se definiam id\u00e9ias sobre tudo. Gerava um equil\u00edbrio natural, pois o dito era submetido ao crivo dos que estavam na plat\u00e9ia. Estes, se revezavam na necessidade de declarar alguma coisa, nem sempre como contraponto ou refor\u00e7o, mas como inaugura\u00e7\u00e3o de novos vetores do assunto.<\/p>\n<p>A presen\u00e7a f\u00edsica foi eliminada, j\u00e1 que tudo obedece \u00e0 privatiza\u00e7\u00e3o predat\u00f3ria. Hoje existem bairros e at\u00e9 mesmo cidades inteiras em que as cal\u00e7adas foram substitu\u00eddas por um fiapo de laje ou grama entre a rua e as casas. \u00c9 que nenhum cent\u00edmetro de \u00e1rea urbana deve escapar da voragem da especula\u00e7\u00e3o. Das cr\u00edticas ao gigantismo do Estado, herdamos apenas a demoli\u00e7\u00e3o pura e simples do que era comum a toda cidadania. Sabemos o que significa pra\u00e7a atualmente: o n\u00e3o-lugar tomado pela exclus\u00e3o e a mis\u00e9ria.<\/p>\n<p>Assim, amontoados nos andares de alimenta\u00e7\u00e3o dos shoppings, ou de p\u00e9 em pisos de m\u00e1rmore (pois \u00e9 preciso circular compulsivamente para comprar sem parar) fomos empurrados para a tela do micro, que aceita tudo. Ali, voc\u00ea se dedica diariamente a eliminar as mensagens n\u00e3o solicitadas, os convites insistentes, as manifesta\u00e7\u00f5es bizarras ou os ataques sem sentido. \u00c9 como defender uma pequena propriedade no meio do nada. A invas\u00e3o vem por toda a parte, pois no imp\u00e9rio da for\u00e7a bruta, quem pode mais acha gra\u00e7a do resto.<\/p>\n<p>Para reinventar a roda, n\u00e3o precisa caluniar o mundo digital ou o com\u00e9rcio selecionado das grifes. Basta aplicar a lei: o espa\u00e7o privado n\u00e3o \u00e9 p\u00fablico e vice-versa.<\/p>\n<p>(<em>Cr\u00f4nica publicada no dia 2 de fevereiro de 2010, na caderno Variedades, do Di\u00e1rio Catarinense<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei Ducl\u00f3s Conv\u00edvio implica altern\u00e2ncia de pap\u00e9is: num momento somos protagonistas, em outro, coadjuvantes. Mas como em terra de escravos todo mundo \u00e9 senhor, para escapar do estigma, a moda \u00e9 impor o papel principal, jogando fora os demais interlocutores. As m\u00eddias sociais s\u00e3o o para\u00edso desse estado de coisas: todos falam ao mesmo tempo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"_links":{"self":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/1978"}],"collection":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/comments?post=1978"}],"version-history":[{"count":1,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/1978\/revisions"}],"predecessor-version":[{"id":1979,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/1978\/revisions\/1979"}],"wp:attachment":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/media?parent=1978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/categories?post=1978"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/tags?post=1978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}