{"id":2168,"date":"2010-07-09T17:48:27","date_gmt":"2010-07-09T20:48:27","guid":{"rendered":"http:\/\/www.consciencia.org\/neiduclos\/?p=2168"},"modified":"2010-07-09T17:48:27","modified_gmt":"2010-07-09T20:48:27","slug":"futebol-para-iniciantes","status":"publish","type":"post","link":"http:\/\/www.consciencia.org\/neiduclos\/futebol-para-iniciantes","title":{"rendered":"FUTEBOL PARA INICIANTES"},"content":{"rendered":"<p><strong>Nei Ducl\u00f3s<\/strong><\/p>\n<p>Sou veterano em futebol. Ajudei a fundar um time h\u00e1 50 anos, que est\u00e1 vivo at\u00e9 hoje, o E.C. Guarani, de Uruguaiana. Fui goleiro da minha rua, da minha classe, do meu col\u00e9gio. Fiz gol no \u00e2ngulo numa aula de educa\u00e7\u00e3o f\u00edsica e outro por cobertura, chutando do canto, que bateu na trave e entrou. Fechei o gol em in\u00fameras ocasi\u00f5es, defendendo v\u00e1rios p\u00eanalties num \u00fanico torneio. Vi gol de Pel\u00e9 ao vivo, no est\u00e1dio Ol\u00edmpico de Porto Alegre. Vi a sele\u00e7\u00e3o de 70 jogar antes de ir para o M\u00e9xico ser tricampe\u00e3.<\/p>\n<p>Sou gremista e corintiano sem nenhum fanatismo, at\u00e9 mesmo com algumas desist\u00eancias c\u00edclicas, quando torcer me enche a paci\u00eancia. Escrevo razoavelmente sobre esporte h\u00e1 v\u00e1rios anos. Acompanho a Copa do Mundo desde 1962. Vejo os principais jogos dos campeonatos estaduais e federais. N\u00e3o sou, portanto, iniciante. E posso pontificar sobre futebol para mostrar alguns caminhos para os iniciantes. N\u00e3o me refiro aos torcedores, que s\u00e3o profissionais do ramo. Mas aos falsos entendidos em futebol, que vivem dizendo coisas na m\u00eddia, que erram todos os progn\u00f3sticos e sentem raiva de t\u00e9cnico da sele\u00e7\u00e3o. Vou dizer como a coisa funciona.<\/p>\n<p>N\u00e3o existe futebol alegre. O que \u00e9 alegre \u00e9 a cena que voc\u00ea comp\u00f5e na mem\u00f3ria. Voc\u00ea junta as melhores lances na cabecinha e acha que esse \u00e9 o futebol brasileiro. Como o paradigma n\u00e3o funciona na pr\u00e1tica, porque futebol d\u00e1 trabalho, voc\u00ea vive se decepcionando, dizendo que este n\u00e3o \u00e9 o futebol brasileiro, e imediatamente migra para o Cristiano Ronaldo, o Drogba, o Messi e quem mais for surgindo na tua frente<\/p>\n<p>O futebol \u00e9 triste como um blues. \u00c9 um jogo que se joga com os p\u00e9s, porra, e n\u00e3o com beija-flores no cocuruto ou borboletas na lapela. Isso n\u00e3o quer dizer que seja obrigatoriamente bruto. S\u00f3 \u00e9 bruto quando o Tevez faz gol impedido no M\u00e9xico ou o Messi d\u00e1 um totozinho, desses que o Ronaldo vive acertando no gol e erra. N\u00e3o \u00e9 bruto quando o capit\u00e3o Lucio ganha a parada, ou Zito e Vav\u00e1 rompem na \u00e1rea, mas quando um cavalo como o Felipe Mello pisoteia o jogador holand\u00eas. Ou seja, h\u00e1 tristeza no futebol, h\u00e1 brutalidade, mas como num blues rascante, h\u00e1 melodia, gra\u00e7a, leveza e grandeza. H\u00e1 chap\u00e9u na \u00e1rea e folha seca. Isso \u00e9 blues, n\u00e3o lambada.<\/p>\n<p>Para voc\u00ea provar o que te digo, quebre a rotina e pense um pouco. Todos os seus progn\u00f3sticos da Copa furaram, porque a realidade no futebol, jogo dial\u00e9tico por excel\u00eancia, que vive imerso em paradoxos, n\u00e3o \u00e9 para o teu bico. Voc\u00ea apostou na Fran\u00e7a, na Inglaterra e que sei eu mais e pronto, foram todos embora. Por que? Porque voc\u00ea \u00e9 um iniciante e acha que \u00e9 entendido. Estava na cara que os farsantes que ludibriaram a Irlanda nas eliminat\u00f3rias, como fizeram os jogadores franceses, tinham perna curta. E que aquele bronco do Rooney nunca foi craque pois isso \u00e9 uma inven\u00e7\u00e3o de voc\u00eas, que n\u00e3o enxergam as evid\u00eancias.<\/p>\n<p>Craque \u00e9 o Elano, que ningu\u00e9m dava nada e fez mais gols que o fen\u00f4meno Messi, que n\u00e3o fez nenhum. \u00c9 o Maicon, que fez gol sem \u00e2ngulo. \u00c9 o Robinho, herdeiro de Pel\u00e9, \u00e9 o Juan, o L\u00facio, n\u00e3o o Ver\u00f3n, o Cag\u00f3n e o Bosti\u00f3n. Entenda, ser estrangeiro \u00e9 uma merda, por isso foi inventado o Brasil, para os estrangeiros se livrarem dessa sina. O mundo inteiro veste a camisa canarinho pentacampe\u00e3 do mundo, s\u00f3 voc\u00eas que n\u00e3o. Por que? Por que s\u00e3o id\u00eanticos ao Maradona, usam \u00f3culos escuros com diamantes e confundem a fa\u00edsca da j\u00f3ia com a pr\u00f3pria identidade. V\u00e3o carpir um lote.<\/p>\n<p>Quando o Brasil \u00e9 eliminado nas quartas de final, n\u00e3o baixem a cal\u00e7as para o Zizou ou o Robben. \u00c9 feio baixar as cal\u00e7as. Deixem as cal\u00e7as postas, as botas postas, o cinto apertado e carreguem a cartucheira que l\u00e1 vem bala. E se perguntem porque milhares de paraguaios celebraram suas conquistas no Mato Grosso. N\u00e3o existe mais fronteira por l\u00e1? Outra coisa: toda vez que voc\u00ea ouvir falar de um homem integro, digno, corajoso, como Dunga, n\u00e3o abra a matraca numa risada estert\u00f3rica. Ponha-se de p\u00e9 em sinal de respeito.<\/p>\n<p>Porque o capit\u00e3o da sele\u00e7\u00e3o canarinho pentacampe\u00e3 do mundo est\u00e1 passando na sua frente. Um patriota lutador \u00e9 raro hoje em dia. Aprenda com ele e n\u00e3o diga tanta asneira. Vai chutar uma bola de meia para ver que a jabulani \u00e9 pinto perto de uma resma de papel amassado no terreno baldio esburacado e \u00edngreme. Vai esfolar o ded\u00e3o, como eu fiz na inf\u00e2ncia para aprender a respeitar os jogadores, aqueles que se quebram em campo defendendo as cores nacionais. N\u00e3o os chame de comerciantes. Alguns s\u00e3o, mas a maioria n\u00e3o.<\/p>\n<p>Goste do seu pa\u00eds, seu coisa, que o pa\u00eds existe para a nossa sobreviv\u00eancia e por ele somos capazes de pegar em armas, que dir\u00e1 formar uma equipe e enfrentar os coxas brancas e os coices de todas as cores em territ\u00f3rios ermos de Brasil, l\u00e1 onde a coruja pia e Deus est\u00e1 na arquibancada vendo como voc\u00ea vai se sair dessa.<\/p>\n<p>Aprenda enquanto estou vivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei Ducl\u00f3s Sou veterano em futebol. Ajudei a fundar um time h\u00e1 50 anos, que est\u00e1 vivo at\u00e9 hoje, o E.C. Guarani, de Uruguaiana. Fui goleiro da minha rua, da minha classe, do meu col\u00e9gio. Fiz gol no \u00e2ngulo numa aula de educa\u00e7\u00e3o f\u00edsica e outro por cobertura, chutando do canto, que bateu na trave [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"_links":{"self":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2168"}],"collection":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/comments?post=2168"}],"version-history":[{"count":1,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2168\/revisions"}],"predecessor-version":[{"id":2169,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2168\/revisions\/2169"}],"wp:attachment":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/media?parent=2168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/categories?post=2168"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/tags?post=2168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}