{"id":2504,"date":"2011-01-15T12:46:43","date_gmt":"2011-01-15T12:46:43","guid":{"rendered":"http:\/\/www.consciencia.org\/neiduclos\/?p=2504"},"modified":"2011-01-15T12:46:43","modified_gmt":"2011-01-15T12:46:43","slug":"litoral","status":"publish","type":"post","link":"http:\/\/www.consciencia.org\/neiduclos\/litoral","title":{"rendered":"LITORAL"},"content":{"rendered":"<p><strong>Nei Ducl\u00f3s<br \/>\n<\/strong><br \/>\nO mundo n\u00e3o cabe no litoral brasileiro, sabemos disso todo santo janeiro. \u00c9 por isso que nos esfor\u00e7amos em expulsar turistas. Providenciamos um mar que engole praias, umas praias sem saneamento b\u00e1sico, uns servi\u00e7os bizarros como o do flanelinha alugando trecho de areia. Sem falar num queijo fedido assado na brasa que insistem em vender. Qual ser\u00e1 a l\u00f3gica de comer churro frio lambuzado de chocolate num calor de 40 graus? E por que o vendedor de cangas se estabelece entre voc\u00ea e a paisagem exatamente no momento em que mil quil\u00f4metros de congestionamento chegaram ao fim para inaugurar o veraneio?<\/p>\n<p>Parece que n\u00e3o adianta. A cada ano chegam mais. Ent\u00e3o intensificamos a oferta. Os crimes aumentam, junto com os pre\u00e7os de coisas b\u00e1sicas, da carne ao sorvete, mas isso n\u00e3o atinge as estat\u00edsticas de infla\u00e7\u00e3o. O cart\u00e3o de cr\u00e9dito \u00e9 como papel em branco, aceita tudo, at\u00e9 chegar a fatura. \u00c9 estranho que a cobran\u00e7a jamais apare\u00e7a na publicidade. Nos an\u00fancios, todos podem tudo, comprar um pa\u00eds e mudar de nacionalidade, mas ningu\u00e9m \u00e9 mostrado de cabe\u00e7a baixa na fila dos inadimplentes.<\/p>\n<p>A alta temporada \u00e9 a realiza\u00e7\u00e3o de um velho sonho: desconectar-se do que nos sustenta para entrarmos numa espiral de gastos sem fim. Funciona assim. Em dezembro, endivida-se a popula\u00e7\u00e3o para que haja presentes. Em janeiro, a d\u00edvida migra dos produtos para os servi\u00e7os, j\u00e1 que todos precisam de atendimento nas f\u00e9rias. O que fazer com a sobra do ano anterior? \u00c9 o momento das liquida\u00e7\u00f5es, j\u00e1 que \u00e9 preciso desovar o estoque para renov\u00e1-lo \u2013 s\u00f3 assim as pessoas poder\u00e3o encarar outra d\u00edvida.<\/p>\n<p>Mas o servi\u00e7o n\u00e3o dura, morre enquanto se consuma. Voc\u00ea s\u00f3 leva para casa um eventual sorriso de boas vindas. Ou o sil\u00eancio poss\u00edvel na madrugada quente que foi aben\u00e7oada por uma chuva. \u00c9 isso que vai trazer de volta esses seres bizarros e incompreens\u00edveis, que moram em lugares sem a vizinhan\u00e7a poderosa do oceano. Como podem sobreviver longe das ondas? Como podem passar o inverno sem ver as baleias francas com seus filhotes ao alcance da nossa m\u00e3o? Ou chegar abril e n\u00e3o se fartar de tainha? Ou chegar janeiro e respirar com al\u00edvio, n\u00e3o pelo turismo invasivo, mas pelo frio que d\u00e1 uma tr\u00e9gua e a Terra, no seu esplendor, desabrocha diante de nossos olhos cansados.<\/p>\n<p><em>Cr\u00f4nica publicada nesta ter\u00e7a-feira, dia 11 de janeiro de 2011, no caderno Variedades, do Di\u00e1rio Catarinense<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei Ducl\u00f3s O mundo n\u00e3o cabe no litoral brasileiro, sabemos disso todo santo janeiro. \u00c9 por isso que nos esfor\u00e7amos em expulsar turistas. Providenciamos um mar que engole praias, umas praias sem saneamento b\u00e1sico, uns servi\u00e7os bizarros como o do flanelinha alugando trecho de areia. Sem falar num queijo fedido assado na brasa que insistem [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"_links":{"self":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2504"}],"collection":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/comments?post=2504"}],"version-history":[{"count":1,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2504\/revisions"}],"predecessor-version":[{"id":2505,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2504\/revisions\/2505"}],"wp:attachment":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/media?parent=2504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/categories?post=2504"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/tags?post=2504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}