{"id":2702,"date":"2011-05-30T13:43:08","date_gmt":"2011-05-30T16:43:08","guid":{"rendered":"http:\/\/www.consciencia.org\/neiduclos\/?p=2702"},"modified":"2011-05-30T13:43:08","modified_gmt":"2011-05-30T16:43:08","slug":"flagra","status":"publish","type":"post","link":"http:\/\/www.consciencia.org\/neiduclos\/flagra","title":{"rendered":"FLAGRA"},"content":{"rendered":"<p><strong>Nei Ducl\u00f3s<\/strong><\/p>\n<p>Faltou luz<br \/>\nna madrugada<br \/>\nS\u00f3 ficou acesa<br \/>\na lua cheia<\/p>\n<p>Fadas fazem luau<br \/>\nem segredo na areia<br \/>\nNingu\u00e9m escuta<br \/>\no barulho da balada<\/p>\n<p>A convite da sereia<br \/>\no marinheiro mergulha<br \/>\nem confian\u00e7a<br \/>\npara o nada<\/p>\n<p>A l\u00e2mpada neon<br \/>\nno resto da plumagem<br \/>\nA l\u00e2mina de prata<br \/>\ncega no conv\u00e9s<\/p>\n<p>Alarido de mulher<br \/>\nati\u00e7a a guerra<br \/>\nO sal da \u00e1gua<br \/>\narrasta os p\u00e9s<\/p>\n<p>De repente o sol<br \/>\ndevassa a praia<br \/>\nflagra o amor<br \/>\natr\u00e1s da pedra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei Ducl\u00f3s Faltou luz na madrugada S\u00f3 ficou acesa a lua cheia Fadas fazem luau em segredo na areia Ningu\u00e9m escuta o barulho da balada A convite da sereia o marinheiro mergulha em confian\u00e7a para o nada A l\u00e2mpada neon no resto da plumagem A l\u00e2mina de prata cega no conv\u00e9s Alarido de mulher ati\u00e7a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2702"}],"collection":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/comments?post=2702"}],"version-history":[{"count":1,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2702\/revisions"}],"predecessor-version":[{"id":2703,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2702\/revisions\/2703"}],"wp:attachment":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/media?parent=2702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/categories?post=2702"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/tags?post=2702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}