{"id":2704,"date":"2011-05-30T13:44:51","date_gmt":"2011-05-30T16:44:51","guid":{"rendered":"http:\/\/www.consciencia.org\/neiduclos\/?p=2704"},"modified":"2011-05-30T13:44:51","modified_gmt":"2011-05-30T16:44:51","slug":"deus-e-o-acaso","status":"publish","type":"post","link":"http:\/\/www.consciencia.org\/neiduclos\/deus-e-o-acaso","title":{"rendered":"DEUS E O ACASO"},"content":{"rendered":"<p><strong>Nei Ducl\u00f3s<\/strong><\/p>\n<p>Tenho torrado no twitter a id\u00e9ia bizarra de que a exist\u00eancia de Deus \u00e9 uma inven\u00e7\u00e3o humana, como se a humanidade datada fosse capaz de gerar a id\u00e9ia do infinito, que \u00e9 marca da divindade na nossa alma, segundo Descartes, o mais racional dos fil\u00f3sofos. A abordagem fundamentalista laica \u00e9 pol\u00edtica, uma arena onde ela se sente \u00e0 vontade pois a aborta o foco da transcend\u00eancia e abre a guarda para in\u00fameras a\u00e7\u00f5es. Serve para justificar a sequ\u00eancia de barbaridades que est\u00e3o sendo cometidas em nome da inexist\u00eancia divina. No fundo, n\u00e3o \u00e9 Deus que est\u00e1 em quest\u00e3o, mas o poder.<\/p>\n<p>Como tenho muitos amigos ateus ou agn\u00f3sticos, que nada tem a ver com esse rolo, abri tamb\u00e9m espa\u00e7o para a diversidade do assunto, j\u00e1 que fechar quest\u00e3o nos levou a muitos mortic\u00ednios. Vamos \u00e0s frases:<\/p>\n<p>\u201cXeque-mate!\u201d, disse Deus. \u201cVamos come\u00e7ar outra\u201d, disse o Acaso.<\/p>\n<p>Deus n\u00e3o joga dados porque sabe o resultado<\/p>\n<p>Acaso \u00e9 o deus laico<\/p>\n<p>Vou fazer a \u00e1gua evaporar em forma de nuvem, que depois vai cair em forma de \u00e1gua. Criei o moto cont\u00ednuo. Ou n\u00e3o me chamo Acaso<\/p>\n<p>O \u00fanico up-grade que deu certo foi o da costela. Mas, tamb\u00e9m, a\u00ed n\u00e3o teve gra\u00e7a. Era Deus em pessoa na programa\u00e7\u00e3o<\/p>\n<p>J\u00e1 sei! disse o Acaso. Vou colocar trilh\u00f5es de corpos celestes boiando misteriosamente, alguns com vida,outros com luz pr\u00f3pria.Nem acredito!<\/p>\n<p>Registro correntes el\u00e9tricas neurobiol\u00f3gicas de intensa atividade por ti, disse o ateu. J\u00e1 eu n\u00e3o sinto porra nenhuma, respondeu a muher<\/p>\n<p>Vou coalhar o c\u00e9u de estrelas no ver\u00e3o e de repente fazer subir a lua cheia.Chamar\u00e3o isso de equin\u00f3cio bilateral, mas o que importa \u00e9 a obra<\/p>\n<p>Na boa. Coloco uma coisa gelatinosa no buraco de um esqueleto e ele tem a capacidade de enxergar.Depois escuto que as amebas come\u00e7aram tudo<\/p>\n<p>\u00c9 simples. Coloco uns corpos boiando no espa\u00e7o, cheios de vida dentro, uma mais complexa do que a outra, e sopro a id\u00e9ia de que n\u00e3o existo<\/p>\n<p>E agora, as sinapses, disse o deus Acaso para si mesmo<\/p>\n<p>O cara mais inoportuno que existe \u00e9 o Tempo. Mas, pior sem ele<\/p>\n<p>Gra\u00e7as aos babacas pseudoreligiosos (os profissionais de Jesus) e aos fundamentalistas, o assunto Deus virou piada<\/p>\n<p>O Acaso n\u00e3o explica nada. \u00c9 apenas um \u00e1libi para negar a evid\u00eancia de Deus<\/p>\n<p>Laico \u00e9 masculino de Laika<\/p>\n<p>No Brasil, ateu usa express\u00e3o &#8220;de alma lavada&#8221;. Devia usar &#8220;de sistema neurobiol\u00f3gico evolutivo lavado&#8221;<\/p>\n<p>Deus n\u00e3o bate p\u00eanalti, nem defende. P\u00eanalti \u00e9 uma negocia\u00e7\u00e3o entre a bola e o p\u00e9<\/p>\n<p>Tudo fazem para sentirmos vergonha da Igreja. Pois eu sinto exatamente o contr\u00e1rio. A f\u00e9 em Deus e na sua Igreja \u00e9 a \u00fanica aliada do povo<\/p>\n<p>S\u00f3 a Igreja Cat\u00f3lica tem que ser ecum\u00eanica. As outras cren\u00e7as, como o ateismo ou agnosticismo, n\u00e3o abrem m\u00e3o de seu c\u00e2none<\/p>\n<p>A laicidade obsessiva \u00e9 um fundamentalismo t\u00e3o opressivo quanto os fundamentalismos religiosos. Nada existe fora dos seus muros<\/p>\n<p>O ateismo \u00e9 natural, assim como os caramujos. Deus \u00e9 um pouco mais acima.<\/p>\n<p>Deus escreve certo at\u00e9 140 caracteres. Mais do que isso \u00e9 fundamentalismo.<\/p>\n<p>Deus n\u00e3o est\u00e1 confinado nas tuas ora\u00e7\u00f5es. Existe tamb\u00e9m fora delas, como a noite infinita ao redor do fogo<\/p>\n<p>Hoje \u00e9 Deus. Amanh\u00e3, s\u00f3 Ele sabe.<\/p>\n<p>Lembre da tua inf\u00e2ncia, quando Deus sentava no portal de casa contigo.<\/p>\n<p>Os est\u00e1dios n\u00e3o tem deuses. Est\u00e1dio n\u00e3o \u00e9 igreja. As bibliotecas n\u00e3o s\u00e3o l\u00fadicas. Biblioteca n\u00e3o \u00e9 play-ground.<\/p>\n<p>Meu vizinho disse que o ficus que grudou na parede da minha casa atra\u00eda el\u00e9trons provocando ventos.Falei: acredito em Deus, mas n\u00e3o no \u00e1tomo<\/p>\n<p>Deus toma notas, n\u00e3o para lembrar, mas para mostrar como prova<\/p>\n<p>Deus recorta o c\u00e9u azul profundo com o olhar, mas a metereologia fala em &#8220;massa de ar seco&#8221;.S\u00f3 a poesia capta o esplendor de mar\u00e7o<\/p>\n<p>POR ACASO, A POESIA<\/p>\n<p>N\u00e3o perca tempo com esses assuntos, disse Jack o Marujo. Prefira as pedras, que s\u00e3o eternas, ou as gar\u00e7as. Abrace a indiferen\u00e7a que liberta<\/p>\n<p>Longevidade \u00e9 quando prescreve o crime de ter nascido<\/p>\n<p>Fantasmas se ofendem ao ser ignorados e fogem para o Tempo Ido, onde tudo obedece aos seus des\u00edgnios. At\u00e9 voc\u00ea, que n\u00e3o os v\u00ea, fica submisso<\/p>\n<p>Embarcamos com a mala gasta cheio de roupas porque \u00e9 inverno, e aguardamos o apito do trem. \u00c9 quando o sonho bate no vidro, desesperado<\/p>\n<p>Depois de passar todos os comboios de palavras in\u00fateis, vemos que na esta\u00e7\u00e3o,o tempo todo,ao nosso lado, brotava o primeiro som de um poema<\/p>\n<p>Beijo qualquer com gosto de Lua, dado ao acaso num l\u00e1bio de rua, volte ao cord\u00e3o que nos viu amarrados, traga a manh\u00e3 ao som do dobrado<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei Ducl\u00f3s Tenho torrado no twitter a id\u00e9ia bizarra de que a exist\u00eancia de Deus \u00e9 uma inven\u00e7\u00e3o humana, como se a humanidade datada fosse capaz de gerar a id\u00e9ia do infinito, que \u00e9 marca da divindade na nossa alma, segundo Descartes, o mais racional dos fil\u00f3sofos. A abordagem fundamentalista laica \u00e9 pol\u00edtica, uma arena [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2704"}],"collection":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/comments?post=2704"}],"version-history":[{"count":1,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2704\/revisions"}],"predecessor-version":[{"id":2705,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2704\/revisions\/2705"}],"wp:attachment":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/media?parent=2704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/categories?post=2704"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/tags?post=2704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}