{"id":2984,"date":"2011-10-30T13:41:00","date_gmt":"2011-10-30T15:41:00","guid":{"rendered":"http:\/\/www.consciencia.org\/neiduclos\/?p=2984"},"modified":"2011-10-30T13:41:00","modified_gmt":"2011-10-30T15:41:00","slug":"arraso","status":"publish","type":"post","link":"http:\/\/www.consciencia.org\/neiduclos\/arraso","title":{"rendered":"ARRASO"},"content":{"rendered":"<p><strong>Nei Ducl\u00f3s<\/strong><\/p>\n<p>Exclusiva como ao sol se fina<br \/>\no \u00faltimo rebento da a\u00e7ucena<br \/>\n\u00fanica solid\u00e3o que te combina<br \/>\npara o mito de ser apenas Lua<\/p>\n<p>Rima de amor, pobre criatura<br \/>\nabandonada na im\u00f3vel grua<br \/>\nnuma constru\u00e7\u00e3o que virou ru\u00edna<br \/>\nem guerra decidida no sub\u00farbio<\/p>\n<p>\u00c9 com esse n\u00f3 que falo ao Tempo<br \/>\nsabendo que serei jogado fora<br \/>\nque importa se terei teu seio<\/p>\n<p>entre as m\u00e3os que agora dormem<br \/>\nDespertarei contigo numa cama<br \/>\nem len\u00e7\u00f3is de flor e cheiro forte<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei Ducl\u00f3s Exclusiva como ao sol se fina o \u00faltimo rebento da a\u00e7ucena \u00fanica solid\u00e3o que te combina para o mito de ser apenas Lua Rima de amor, pobre criatura abandonada na im\u00f3vel grua numa constru\u00e7\u00e3o que virou ru\u00edna em guerra decidida no sub\u00farbio \u00c9 com esse n\u00f3 que falo ao Tempo sabendo que serei [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2984"}],"collection":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/comments?post=2984"}],"version-history":[{"count":1,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2984\/revisions"}],"predecessor-version":[{"id":2985,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/2984\/revisions\/2985"}],"wp:attachment":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/media?parent=2984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/categories?post=2984"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/tags?post=2984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}