{"id":3116,"date":"2011-11-26T15:52:27","date_gmt":"2011-11-26T17:52:27","guid":{"rendered":"http:\/\/www.consciencia.org\/neiduclos\/?p=3116"},"modified":"2012-01-01T10:11:45","modified_gmt":"2012-01-01T12:11:45","slug":"dialogos-impossiveis","status":"publish","type":"post","link":"http:\/\/www.consciencia.org\/neiduclos\/dialogos-impossiveis","title":{"rendered":"DI\u00c1LOGOS IMPOSS\u00cdVEIS"},"content":{"rendered":"<p><strong>Nei Ducl\u00f3s<\/strong><\/p>\n<p>E onde pomos o cora\u00e7\u00e3o? disse o sujeito da mudan\u00e7a. Deixa na cal\u00e7ada, algu\u00e9m h\u00e1 de levar. Ela n\u00e3o deu falta, mesmo<\/p>\n<p>J\u00e1 passa da hora, disse o guarda noturno. Te manda. S\u00f3 mais uns minutos, disse o Sonho. Algu\u00e9m deve passar por aqui e me dar uma carona<\/p>\n<p>Sei que n\u00e3o vais abrir a porta,disse o Remorso.Mas deixo o que colhi nesta noite ingl\u00f3ria:a dor de te perder e o cheiro do teu corpo molhado<\/p>\n<p>A cria\u00e7\u00e3o parou? perguntou o anjo.Est\u00e3o faltando asas nas pessoas. Hor\u00e1rio de almo\u00e7o, disse Deus.Depois, sesta.Talvez n\u00e3o acabe esse servi\u00e7o<\/p>\n<p>Agora est\u00e1 de bom tamanho, disse a patriarca. Deixaste tudo para voltar a este fim de mundo. Ele ainda mora l\u00e1? perguntou a filha pr\u00f3diga<\/p>\n<p>Vamos fechar a biblioteca, disse a veterana. S\u00f3 falta a \u00faltima p\u00e1gina, quando ela volta, diz o garoto. A sra vai querer que eu morra?<\/p>\n<p>N\u00e3o temos vaga para o sr, disse o consultor. Mas voc\u00eas precisam de cartas de boas vindas, disse o missivista profissional. Fa\u00e7o pela comida<\/p>\n<p>Conseguimos zerar o sentimento, disse o diretor corporativo. Ela foi mandada embora? perguntou o presidente, aos prantos<\/p>\n<p>Seu texto est\u00e1 muito bom, mas peca pelo excesso,disse o publisher.N\u00e3o serve para nossa p\u00e1gina de editoriais.Vamos colocar no correio amoroso<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei Ducl\u00f3s E onde pomos o cora\u00e7\u00e3o? disse o sujeito da mudan\u00e7a. Deixa na cal\u00e7ada, algu\u00e9m h\u00e1 de levar. Ela n\u00e3o deu falta, mesmo J\u00e1 passa da hora, disse o guarda noturno. Te manda. S\u00f3 mais uns minutos, disse o Sonho. Algu\u00e9m deve passar por aqui e me dar uma carona Sei que n\u00e3o vais [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[306],"tags":[],"_links":{"self":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/3116"}],"collection":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/comments?post=3116"}],"version-history":[{"count":2,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/3116\/revisions"}],"predecessor-version":[{"id":3277,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/3116\/revisions\/3277"}],"wp:attachment":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/media?parent=3116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/categories?post=3116"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/tags?post=3116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}