{"id":3577,"date":"2012-03-16T16:20:31","date_gmt":"2012-03-16T19:20:31","guid":{"rendered":"http:\/\/www.consciencia.org\/neiduclos\/?p=3577"},"modified":"2012-03-16T16:20:31","modified_gmt":"2012-03-16T19:20:31","slug":"mudanca","status":"publish","type":"post","link":"http:\/\/www.consciencia.org\/neiduclos\/mudanca","title":{"rendered":"MUDAN\u00c7A"},"content":{"rendered":"<p><strong>Nei Ducl\u00f3s<\/strong><\/p>\n<p>Escrevi no teu muro, eu n\u00e3o sabia mas tinhas te mudado. S\u00f3 viste a frase anos mais tarde, quando passaste pela rua para matar a saudade. Dizia: n\u00e3o v\u00e1 embora, te amo. Soube que choraste.<\/p>\n<p>A mais bela est\u00e1 em sil\u00eancio. A terra inteira participa do segredo.<\/p>\n<p>Ela recolheu-se. Dor, vertigem, talvez apenas cansa\u00e7o. Confluem as \u00e1guas para seu rega\u00e7o.<\/p>\n<p>Nem me dei conta. Me querias.<\/p>\n<p>Como algu\u00e9m pode pirar por outra pessoa sem nenhum motivo? Talvez as coisas se decidam na massa escura do universo, a que nos rodeia e ningu\u00e9m v\u00ea. L\u00e1 trabalham firme os anjos.<\/p>\n<p>O teatro estava fechado e todos esqueceram dele. At\u00e9 que arrombaram as portas e viram a poesia dormindo embaixo do palco.<\/p>\n<p>Sonhei contigo, meu amor. Tinhas voltado.<\/p>\n<p>Depois que terminamos, sinto que o livro de amor chega ao limite. Voltarei \u00e0 guerra, s\u00f3 de vingan\u00e7a.<\/p>\n<p>O destino demitiu-me do teu conv\u00edvio. Onde estar\u00e1 teus passos, encantada?<\/p>\n<p>Falarei de batalhas e conquistas. Deixarei de lado tuas chaves. Basta de brincar de amor, mais mortal que qualquer refrega.<\/p>\n<p>Vou me alistar, a\u00e7ucena. Nem levarei uma foto tua. Terei olhos apenas para os alvos, que rebentarei sem l\u00e1grimas<\/p>\n<p>N\u00e3o quero ficar perto. O amor morde.<\/p>\n<p>N\u00e3o espero despedidas. Estarei ocupado, limpando as armas. O apito do trem me levar\u00e1 para longe. Escuta o cora\u00e7\u00e3o chorando, porque ele ainda te pertence.<\/p>\n<p>Ningu\u00e9m acreditar\u00e1 que a mais bela faz parte do meu sonho. N\u00e3o terei provas. A n\u00e3o ser alguns arranh\u00f5es no rosto roto e no corpo escasso.<\/p>\n<p>Chegou uma carta para o senhor, disse o encarregado. Era dela. Nenhuma palavra, apenas uma gota de perfume do seu choro.<\/p>\n<p>Pensa que n\u00e3o sei que teu sil\u00eancio \u00e9 amor? N\u00e3o por mim, porque se rompeu o la\u00e7o. Mas pelo que fomos, dois apaixonados.<\/p>\n<p>Voc\u00ea n\u00e3o a merecia, me disse o soldado me alcan\u00e7ando uma carga de metralha. Agora atira e escuta a saudade queimando a p\u00f3lvora.<\/p>\n<p>Quando assinarem a paz, estarei livre de novo. Partirei para o Oriente para n\u00e3o ter de enfrentar de novo teu sil\u00eancio.<\/p>\n<p>Sou teu segredo. N\u00e3o espera que eu grite, princesa?<\/p>\n<p>Desta vez n\u00e3o ter\u00e1 volta. Se sobreviver ficarei por aqui mesmo, contando os mortos. O comboio partir\u00e1 cedo. N\u00e3o adianta me esperar com aquele vestido claro e o batom vermelho.<\/p>\n<p>E aquele amor em banho Maria que n\u00e3o desatava? De repente toma impulso, assim do nada. Vai entender Cupido, o deus travesso.<\/p>\n<p>Voc\u00ea enfim desiste e vai-se para todo o sempre. Mas da janela do trem v\u00eas ent\u00e3o que ela te acompanha, de jipe, pela ravina, a toda. Implicante.<\/p>\n<p>Ela me cita, mas junto com outros nomes. Para disfar\u00e7ar, a ordin\u00e1ria. Vou exterminar a companhia.<\/p>\n<p>Te trouxe escondida no bolso. Passamos pelas barreiras. Depois desembrulhei e todinha te estiraste na areia. Seren\u00edssima.<\/p>\n<p>N\u00e3o conte para ningu\u00e9m, promete? Fico sem jeito quando descobrem que ainda tenho um cora\u00e7\u00e3o.<\/p>\n<p>Continue disfar\u00e7ando. \u00c0 meia noite vamos ver o que \u00e9 bom para a tosse.<\/p>\n<p>Fique fora do alcance, assim n\u00e3o descobrem. Aguarde que eu tenho como chegar. Cavei um t\u00fanel. Sintonize as ondas curtas.<\/p>\n<p>H\u00c1BITO<\/p>\n<p>Foi bonito o amor, mas mataram. At\u00e9 a pr\u00f3xima paix\u00e3o.<\/p>\n<p>Sensa\u00e7\u00e3o de vidro quebrado. S\u00f3 agora entendi.<\/p>\n<p>Qualquer pensamento raspa naquela superf\u00edcie afiada, que corta fundo parecendo fino.<\/p>\n<p>Voc\u00ea tinha previsto. Agora vejo. Fica assim, portento?<\/p>\n<p>Que adianta recome\u00e7ar se continuar\u00e1 o mesmo? Eu te querendo e voc\u00ea no lado oculto da Lua.<\/p>\n<p>A n\u00e3o ser que voc\u00ea deixe eu lhe tirar as meias<\/p>\n<p>Mas deves estar ocupada em n\u00e3o me querer.<\/p>\n<p>Quantas quiseram e eu cedi, pensando em ti. Gastei \u00e0 toa minhas vontades<\/p>\n<p>N\u00e3o quero ficar longe. O amor n\u00e3o deixa.<\/p>\n<p>Venceu a data do sil\u00eancio. Fui derrotado. Agora vibre a f\u00e1brica do amor que estava de quarentena.<\/p>\n<p>Achou? ela perguntou. N\u00e3o, disse ele. A mar\u00e9 levou. Agora como abro a porta do teu cora\u00e7\u00e3o? N\u00e3o posso for\u00e7ar.<\/p>\n<p>Continuo com o mesmo h\u00e1bito. Dou bom dia na hora de embarcar, boa tarde junto com os ventos, e te beijo antes de dormir, para que sonhes acordando ao meu lado.<\/p>\n<p>N\u00e3o se desmanche na hora de dizer. Se recomponha. A palavra enxuta sabe beijar melhor.<\/p>\n<p>Ningu\u00e9m sabe o que se passa na sua cabe\u00e7a. N\u00e3o d\u00ea bandeira. Fa\u00e7a cara de penhasco a beira mar.<\/p>\n<p>Guarde os versos numa caixa de m\u00fasica. Toda vez que abrir, dan\u00e7ar\u00e1s ao som da valsa.<\/p>\n<p>Eu j\u00e1 estava desistindo, mas fiquei com esperan\u00e7a.<\/p>\n<p>J\u00e1 que n\u00e3o respondes, vou me transformar na pergunta. Sempre que escutares meu nome, saber\u00e1s do que se trata.<\/p>\n<p>\u00c9 t\u00e3o dificil acertar. Na prova do amor, precisamos colar.<\/p>\n<p>Jamais iria te assediar. Amo voc\u00ea demais para isso.<\/p>\n<p>Armei a isca e fiquei esperando. Voc\u00ea se aproximou e disse: que livro \u00e9 esse?<\/p>\n<p>TEMPOS<\/p>\n<p>J\u00e1 vi tudo, disse o indiferente.<\/p>\n<p>Parab\u00e9ns pelas pedras, disse o anjo. Duram eternamente. E o resto da Cria\u00e7\u00e3o? O resto obedecer\u00e1 ao paradigma chin\u00eas, disse o Senhor.<\/p>\n<p>Destruam tudo, disse o chefe. Qualquer coisa, foi Deus<\/p>\n<p>Cuidado. Sexo pode provocar independ\u00eancia f\u00edsica.<\/p>\n<p>Os Tempos s\u00e3o garotos maus. Mas se arrumam e colocam roupa limpa quando recebem visita da tia Mem\u00f3ria.<\/p>\n<p>PESADA DE LUZ<\/p>\n<p>Agora sim a Lua. Custou a sair porque est\u00e1 mais pesada de luz.<\/p>\n<p>A Cheia aparece majestosa acima dos telhados, ro\u00e7ando o horizonte do sereno que come\u00e7a a cair, r\u00fatila sobre o mundo, rainha suprema da luz e do poema.<\/p>\n<p>Faz-se o sil\u00eancio no mundo insano. A Eterna sobe aos c\u00e9us cavalgando nossa esperan\u00e7a.<\/p>\n<p>Quem poder\u00e1 negar seu poder? Decifra-nos, rainha, para que possamos celebrar a tua majestade<\/p>\n<p>No ombro dos gigantes, ela evolui seu infinito charme sobre nossos olhos em suspense<\/p>\n<p>Nuvem se esgar\u00e7a quando passa pela Lua. Como se fosse fuma\u00e7a de um trem de luz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei Ducl\u00f3s Escrevi no teu muro, eu n\u00e3o sabia mas tinhas te mudado. S\u00f3 viste a frase anos mais tarde, quando passaste pela rua para matar a saudade. Dizia: n\u00e3o v\u00e1 embora, te amo. Soube que choraste. A mais bela est\u00e1 em sil\u00eancio. A terra inteira participa do segredo. Ela recolheu-se. Dor, vertigem, talvez apenas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[306],"tags":[],"_links":{"self":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/3577"}],"collection":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/comments?post=3577"}],"version-history":[{"count":1,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/3577\/revisions"}],"predecessor-version":[{"id":3579,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/3577\/revisions\/3579"}],"wp:attachment":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/media?parent=3577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/categories?post=3577"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/tags?post=3577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}