{"id":3801,"date":"2014-01-18T17:25:07","date_gmt":"2014-01-18T19:25:07","guid":{"rendered":"http:\/\/www.consciencia.org\/neiduclos\/?p=3801"},"modified":"2014-01-20T08:19:34","modified_gmt":"2014-01-20T10:19:34","slug":"blue-jasmine-a-queda-segundo-woody-allen","status":"publish","type":"post","link":"http:\/\/www.consciencia.org\/neiduclos\/blue-jasmine-a-queda-segundo-woody-allen","title":{"rendered":"BLUE JASMINE: A QUEDA, SEGUNDO WOODY ALLEN"},"content":{"rendered":"<p><strong>Nei Ducl\u00f3s<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>A dana\u00e7\u00e3o \u00e9 perder a segunda chance. Na contram\u00e3o da cultura americana, que sempre aposta na volta por cima dos perdedores, a queda, em Blue Jasmine, de Woody\u00a0 Allen, \u00e9 sobre a verdadeira natureza dos vitoriosos, ou seja, sua voca\u00e7\u00e3o para o desastre. Destino n\u00e3o definido pela natureza humana ou pela luta de classes, mas pelo cinema. Cate Blanchett \u00e9\u00a0 o vest\u00edgio de uma situa\u00e7\u00e3o de conforto, que ao rolar para o abismo ocupa espa\u00e7o na periferia do dinheiro representado pelo apartamento brega, a irm\u00e3 pobre e os namorados grosseiros.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Trata-se de cen\u00e1rios e figurinos pontuados pela narrativa das falas dos personagens. E da montagem que alterna a mem\u00f3ria a princ\u00edpio deslumbrada em dire\u00e7\u00e3o ao tombo com o impacto do presente sem solu\u00e7\u00e3o ou sa\u00edda. A protagonista cava sua trag\u00e9dia ao virar o rosto para o outro lado quando o marido lhe enche de fortuna sem perguntar de onde vem tudo aquilo. E ao mentir quando poderia ter dito a verdade para que sua segunda chance passasse pelo teste e encontrasse um desfecho favor\u00e1vel.<\/p>\n<p>&nbsp;<\/p>\n<p>O para\u00edso onde ela se movimenta na mem\u00f3ria \u00e9 falso, cevado pela economia marginal, a caixa 2 dos contratos criminosos, a especula\u00e7\u00e3o ou o roubo puro e simples de poupan\u00e7as alheias. O casal primordial \u00e9 composto por um Ad\u00e3o culpado e uma Eva seduzida e cega. A mordida na ma\u00e7\u00e3 \u00e9 a den\u00fancia depois da descoberta de uma trai\u00e7\u00e3o e o arcanjo \u00e9 a Lei que prende o marido na rua e o leva para a morte na pris\u00e3o. Condenada a ganhar o p\u00e3o do suor do seu rosto, a ex-milion\u00e1ria \u00e9 submetia ao ass\u00e9dio, ao confronto com o passado e \u00e0 mis\u00e9ria. Resta-lhe algumas lembran\u00e7as, como bolsas caras, vestidos de festa, utens\u00edlios de marca. Que funcionam at\u00e9 o limite da transpar\u00eancia, quando a verdade vem mais uma vez \u00e0 tona.<\/p>\n<p>&nbsp;<\/p>\n<p>Falar sozinha na rua dispensando o interlocutor \u00e9 a insanidade provocada pelos sucessivos traumas, que desmancham a int\u00e9rprete de maneira arrasadora, numa performance antol\u00f3gica. Eva leva a culpa de tudo e n\u00e3o h\u00e1 lugar no mundo para ela. Quando havia dinheiro, n\u00e3o havia base para a situa\u00e7\u00e3o se sustentar pois a fam\u00edlia vivia \u00e0 margem da lei. Na pobreza, a solidez da realidade \u00e9 o pesadelo de quem usufruiu da riqueza e n\u00e3o se sintoniza com a possibilidade de um retorno.<\/p>\n<p>&nbsp;<\/p>\n<p>Quebra-se assim o mito do sucesso financeiro, revelando a insustent\u00e1vel leveza do sistema, feito de mentiras. N\u00e3o h\u00e1 tamb\u00e9m honra no mundo prec\u00e1rio dos despossu\u00eddos, prisioneiros dos seus fracassos, que exasperam a ex-madame agora \u00e0s voltas com suas origens pobres. A ascens\u00e3o social \u00e9 uma impossibilidade no mundo hostil.\u00a0 O \u00fanico happy end \u00e9 a m\u00fasica inesquec\u00edvel, Blue Moon. \u00c9 a cultura que costura os farrapos humanos e n\u00e3o lembrar da letra ou perder as pistas da melodia que some num piano distante \u00e9 a verdadeira trag\u00e9dia.\u00a0 Se o cinema, neste caso, \u00e9 den\u00fancia sobre a queda, a can\u00e7\u00e3o \u00e9 a arqueologia de um sonho chamado humanidade que s\u00f3 existe quando acordamos para dentro, salvando o cora\u00e7\u00e3o antes transformado em pedra.<\/p>\n<p>&nbsp;<\/p>\n<p>Fica o desespero da mulher que assumiu o nome da flor que \u00e9 celebrada \u00e0 noite, perfume do jasmin que se espalha pelo tempo. Ela perdeu-se em suas duas oportunidades. Foi desmascarada, expulsa do para\u00edso verdadeiro, que \u00e9 a chance de amar, foram dos tr\u00e2mites da vida perversa. Cate Blanchett tem tudo: talento, f\u00f4lego, garra. E principalmente classe. Ou ganha o Oscar ou esse pr\u00eamio n\u00e3o vale nada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei Ducl\u00f3s &nbsp; A dana\u00e7\u00e3o \u00e9 perder a segunda chance. Na contram\u00e3o da cultura americana, que sempre aposta na volta por cima dos perdedores, a queda, em Blue Jasmine, de Woody\u00a0 Allen, \u00e9 sobre a verdadeira natureza dos vitoriosos, ou seja, sua voca\u00e7\u00e3o para o desastre. Destino n\u00e3o definido pela natureza humana ou pela luta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,308],"tags":[],"_links":{"self":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/3801"}],"collection":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/comments?post=3801"}],"version-history":[{"count":2,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/3801\/revisions"}],"predecessor-version":[{"id":3813,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/posts\/3801\/revisions\/3813"}],"wp:attachment":[{"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/media?parent=3801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/categories?post=3801"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.consciencia.org\/neiduclos\/wp-json\/wp\/v2\/tags?post=3801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}